{"id":52666,"date":"2025-11-02T00:14:00","date_gmt":"2025-11-01T23:14:00","guid":{"rendered":"https:\/\/sonntagsgedanken.de\/blog\/?p=52666"},"modified":"2025-10-31T09:15:36","modified_gmt":"2025-10-31T08:15:36","slug":"wesentlich","status":"publish","type":"post","link":"https:\/\/sonntagsgedanken.de\/blog\/2025\/11\/02\/wesentlich\/","title":{"rendered":"Wesentlich"},"content":{"rendered":"\n<p>Meine Lieben,<\/p>\n\n\n\n<p>in den n\u00e4chsten Wochen mu\u00df ich mir wirklich Zeit f\u00fcr die Sonntagsgedanken aus den Rippen schneiden! Habe gerade \u201eAnna Karenina\u201c beendet und jetzt begonnen, \u201eKrieg und Frieden\u201c von Tolstoi zu lesen, das hei\u00dft, mit Verz\u00f6gerung angefangen.<\/p>\n\n\n\n<p>Die Verz\u00f6gerung kam dadurch, da\u00df ich zun\u00e4chst eine gebundene Ausgabe von Reclam hatte. Die alte Schrift vom Anfang des letzten Jahrhunderts hat mich nicht gest\u00f6rt, das war kein Problem, aber so ein Reclam-B\u00fcchlein, auch gebunden, ist doch sehr klein.<\/p>\n\n\n\n<p>So habe ich beschlossen, mir eine neuere Ausgabe, gr\u00f6\u00dfer und mit normaler, moderner Schrift zu kaufen. Da ich schon drei Kapitel in der alten Reclam-Ausgabe gelesen hatte, fiel mir auf, da\u00df in der Ausgabe vom Nicol Verlag doch einiges sehr verwunderlich war! Da erscheint die Tochter des F\u00fcrsten Wassili in einem Kleid zum Abiturientenball und holt ihren Vater statt zu einem Fest bei englischen Gesandten zu einer \u201eFete\u201c ab.<\/p>\n\n\n\n<p>Fete! Also bitte, bei Tolstoi!<br>Das ist doch bestimmt eine KI-\u00dcbersetzung!<\/p>\n\n\n\n<p>Jetzt habe ich begonnen, eine andere Ausgabe zu lesen, \u00fcbersetzt von Barbara Conrad, wunderbar!<\/p>\n\n\n\n<p>Also, wenn ihr jemals Tolstoi gelesen habt, wisst ihr wahrscheinlich, da\u00df man davon nur schlecht wegkommt, deswegen der Spruch zu Beginn dieses Briefes mit den besagten Rippen.<\/p>\n\n\n\n<p>Na gut, mir wird schon etwas f\u00fcr meine sonnt\u00e4glichen Gedanken in den Sinn kommen, beim Autofahren kann ich ja nicht lesen und die meisten Ideen kommen mir oft genau da, auf dem Weg vom See nach Hofheim oder umgekehrt, eigentlich eher auf dem Weg nach Hofheim.<br>Warum? Keine Ahnung.<br>Vielleicht weil ich auf dem Nachhauseweg an den See schon denke, was ich noch in den n\u00e4chsten Tagen zu erledigen habe.<\/p>\n\n\n\n<p>Naja, ist ja auch egal.<br>Hauptsache, es wird irgendein wesentlicher oder vielleicht auch unwesentlicher Gedanke nach oben geschwenkt.<\/p>\n\n\n\n<p>Man mu\u00df eigentlich sagen, da\u00df es Unwesentliches gar nicht gibt. Vieles scheint zwar nicht so wichtig, aber oft werden aus kleinen Anf\u00e4ngen gro\u00dfe Freuden, manchmal gro\u00dfes Leid. Es beginnt immer klein \u2026 Bei der Liebe mit Verliebtheit, und wenn man dann Gl\u00fcck hat, bleibt das so und verwandelt sich \u00fcber die Jahre in wahre Liebe und wird immer gr\u00f6\u00dfer, hoffentlich.<\/p>\n\n\n\n<p>Wir sitzen und schauen ins Feuer, kleine Flammen lecken am Holz, werden gro\u00df, gr\u00f6\u00dfer, es brennt. Wir r\u00fccken etwas weg mit dem Stuhl vom Kamin, es ist zu warm, ein Schluck Wein, vorn\u00fcber gebeugt betrachten wir die roten Feuerzungen.<\/p>\n\n\n\n<p>So geht\u2019s dahin.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Always Heading Home\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/xOqOMaSrBrI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Ich w\u00fcnsche euch einen interessanten Sonntag.<br>Streitet nicht, haltet zusammen und pa\u00dft auf euch auf.<br>Love and Peace<\/p>\n\n\n\n<p>Euer Eckhard\/Papa\/Opa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Meine Lieben, in den n\u00e4chsten Wochen mu\u00df ich mir wirklich Zeit f\u00fcr die Sonntagsgedanken aus den Rippen schneiden! Habe gerade \u201eAnna Karenina\u201c beendet und jetzt begonnen, \u201eKrieg und Frieden\u201c von Tolstoi zu lesen, das hei\u00dft, mit Verz\u00f6gerung angefangen. Die Verz\u00f6gerung kam dadurch, da\u00df ich zun\u00e4chst eine gebundene Ausgabe von Reclam hatte. Die alte Schrift vom Anfang des letzten Jahrhunderts hat mich nicht gest\u00f6rt, das war kein Problem, aber so ein Reclam-B\u00fcchlein, auch gebunden, ist doch&#8230;<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/sonntagsgedanken.de\/blog\/2025\/11\/02\/wesentlich\/\">mehr<span class=\"screen-reader-text\">Wesentlich<\/span><\/a><\/div>\n","protected":false},"author":2,"featured_media":52661,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","spay_email":""},"categories":[1],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/sonntagsgedanken.de\/blog\/wp-content\/uploads\/2025\/10\/2.jpg?fit=2560%2C1707&ssl=1","_links":{"self":[{"href":"https:\/\/sonntagsgedanken.de\/blog\/wp-json\/wp\/v2\/posts\/52666"}],"collection":[{"href":"https:\/\/sonntagsgedanken.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sonntagsgedanken.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sonntagsgedanken.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sonntagsgedanken.de\/blog\/wp-json\/wp\/v2\/comments?post=52666"}],"version-history":[{"count":1,"href":"https:\/\/sonntagsgedanken.de\/blog\/wp-json\/wp\/v2\/posts\/52666\/revisions"}],"predecessor-version":[{"id":52667,"href":"https:\/\/sonntagsgedanken.de\/blog\/wp-json\/wp\/v2\/posts\/52666\/revisions\/52667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sonntagsgedanken.de\/blog\/wp-json\/wp\/v2\/media\/52661"}],"wp:attachment":[{"href":"https:\/\/sonntagsgedanken.de\/blog\/wp-json\/wp\/v2\/media?parent=52666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sonntagsgedanken.de\/blog\/wp-json\/wp\/v2\/categories?post=52666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sonntagsgedanken.de\/blog\/wp-json\/wp\/v2\/tags?post=52666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}